{"id":28906,"date":"2025-05-11T01:09:30","date_gmt":"2025-05-10T23:09:30","guid":{"rendered":"https:\/\/suittoeyewear.com\/modelo\/granados\/"},"modified":"2025-05-24T11:02:00","modified_gmt":"2025-05-24T09:02:00","slug":"granados","status":"publish","type":"product","link":"https:\/\/suittoeyewear.com\/ca\/model\/granados\/","title":{"rendered":"GRANADOS"},"content":{"rendered":"<p>El Granados, nascut el 1956 a Lleida, \u00e9s un dol\u00e7 que evoca l&#8217;eleg\u00e0ncia i la nost\u00e0lgia de la m\u00fasica del pianista Enric Granados. Amb una textura cruixent d&#8217;ametlla i un sabor subtil, aquest past\u00eds ressalta la bellesa de l&#8217;artesanal. El disseny imperfecte per\u00f2 sublim reflecteix l&#8217;ess\u00e8ncia de la tradici\u00f3 catalana, un delicat homenatge a l&#8217;art i la natura.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Granados, nascut el 1956 a Lleida, \u00e9s un dol\u00e7 que evoca l&#8217;eleg\u00e0ncia i la nost\u00e0lgia de la m\u00fasica del pianista Enric Granados. Amb una textura cruixent d&#8217;ametlla i un sabor subtil, aquest past\u00eds ressalta la bellesa de l&#8217;artesanal. El disseny imperfecte per\u00f2 sublim reflecteix l&#8217;ess\u00e8ncia de la tradici\u00f3 catalana, un delicat homenatge a l&#8217;art [&hellip;]<\/p>\n","protected":false},"featured_media":22234,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[388,393],"product_tag":[340,341],"class_list":["post-28906","product","type-product","status-publish","has-post-thumbnail","product_cat-sybarite-ca","product_cat-sybarite-home","product_tag-novetat","product_tag-vista-ca-2","pa_tonalidad-de-color-01-ca","pa_tonalidad-de-color-23-ca","pa_tonalidad-de-color-72-ca","pa_tonalidad-de-color-79-ca","first","instock","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/suittoeyewear.com\/ca\/wp-json\/wp\/v2\/product\/28906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suittoeyewear.com\/ca\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/suittoeyewear.com\/ca\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suittoeyewear.com\/ca\/wp-json\/wp\/v2\/media\/22234"}],"wp:attachment":[{"href":"https:\/\/suittoeyewear.com\/ca\/wp-json\/wp\/v2\/media?parent=28906"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/suittoeyewear.com\/ca\/wp-json\/wp\/v2\/product_brand?post=28906"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/suittoeyewear.com\/ca\/wp-json\/wp\/v2\/product_cat?post=28906"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/suittoeyewear.com\/ca\/wp-json\/wp\/v2\/product_tag?post=28906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}